{"id":7284,"date":"2022-07-29T15:01:15","date_gmt":"2022-07-29T13:01:15","guid":{"rendered":"https:\/\/www.eddh-airport.de\/eddhairport\/?p=7284"},"modified":"2022-07-29T15:01:15","modified_gmt":"2022-07-29T13:01:15","slug":"aeroitalia-9h-gef","status":"publish","type":"post","link":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/","title":{"rendered":"Aeroitalia, 9H-GEF"},"content":{"rendered":"<h6>Aeroitalia, 9H-GEF<\/h6>\n<p>Vor weit mehr als eine Monat besuchte die italienische Aeroitalia zum ersten Mal den Hamburger Flughafen (<a href=\"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-cri\/\">wir berichteten<\/a>). Am heutigen Morgen erfolgte der zweite Besuch einer Maschine der Charterfluggesellschaft. Mit 9H-GEF landete dabei die zweite Maschine der Flotte in Fuhlsb\u00fcttel auf der Runway 05. Gestartet war die Boeing 737-86Q(WL) zuvor in Berlin (BER) und legte hier auf ihrem Weg zum spanischen Flughafen M\u00e1laga &#8211; Costa del Sol (AGP) lediglich einen Zwischenstopp ein.<\/p>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/519400\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/519400\/\"><span style=\"font-size: xx-small;\">9H-GEF at Hamburg &#8211; Fuhlsbuettel (Helmut Schmidt)<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><\/p>\n<p>Der mehr als 19 Jahre alte Zweistrahler k\u00f6nnte dem ein oder anderen eventuell bekannt vorkommen. So war das Mittelstreckenflugzeug nach seiner Auslieferung im amerikanischen Renton (RNT) am 19. Februar 2003 einige Jahre als D-ABBJ f\u00fcr Air Berlin im Einsatz. Erst am 22. April 2015 \u00fcbernahm dann die belarussische Belavia die 737. Dort flog sie bis zum 2. November 2021 und wurde dann in Istanbul (IST), Woensdrecht (WOE), Belgrad (BEL) und Amsterdam (AMS) geparkt. Erst vor einigen Tagen, am 18. Juli, wurde die Boeing dann ins italienische Forli (FRL) \u00fcberf\u00fchrt und ist nun sogar erst seit sechs Tagen aktiv im Dienst der Aeroitalia als 9H-GEF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aeroitalia, 9H-GEF Vor weit mehr als eine Monat besuchte die italienische Aeroitalia zum ersten Mal den Hamburger Flughafen (wir berichteten). Am heutigen Morgen erfolgte der zweite Besuch einer Maschine der Charterfluggesellschaft. Mit 9H-GEF landete dabei die zweite Maschine der Flotte in Fuhlsb\u00fcttel auf der Runway 05. Gestartet war die Boeing 737-86Q(WL) zuvor in Berlin (BER) [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[52,424,1426,39,40,29,423,468,10,11,90],"class_list":["post-7284","post","type-post","status-publish","format-standard","hentry","category-movements-eddh","tag-52","tag-737-800","tag-aeroitalia","tag-b737","tag-b737-800","tag-boeing","tag-boeing-737","tag-boeing-737-800","tag-eddh","tag-ham","tag-hamburg-airport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aeroitalia, 9H-GEF - eddh-airport<\/title>\n<meta name=\"description\" content=\"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aeroitalia, 9H-GEF - eddh-airport\" \/>\n<meta property=\"og:description\" content=\"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/\" \/>\n<meta property=\"og:site_name\" content=\"eddh-airport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eddhairport\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-29T13:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg\" \/>\n<meta name=\"author\" content=\"Niclas Rebbelmund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:site\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niclas Rebbelmund\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/\"},\"author\":{\"name\":\"Niclas Rebbelmund\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\"},\"headline\":\"Aeroitalia, 9H-GEF\",\"datePublished\":\"2022-07-29T13:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/\"},\"wordCount\":189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/519400\\\/hottestbrick_main.jpg\",\"keywords\":[\"737\",\"737-800\",\"Aeroitalia\",\"B737\",\"B737-800\",\"Boeing\",\"Boeing 737\",\"Boeing 737-800\",\"EDDH\",\"HAM\",\"Hamburg Airport\"],\"articleSection\":[\"Movements EDDH\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/\",\"name\":\"Aeroitalia, 9H-GEF - eddh-airport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/519400\\\/hottestbrick_main.jpg\",\"datePublished\":\"2022-07-29T13:01:15+00:00\",\"description\":\"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/519400\\\/hottestbrick_main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/519400\\\/hottestbrick_main.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/aeroitalia-9h-gef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aeroitalia, 9H-GEF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"name\":\"eddh-airport\",\"description\":\"Luftfahrtnews und Planespotting aus Hamburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\",\"name\":\"eddh-airport\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"width\":512,\"height\":512,\"caption\":\"eddh-airport\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eddhairport\\\/\",\"https:\\\/\\\/x.com\\\/EDDH_airport_de\",\"https:\\\/\\\/www.instagram.com\\\/eddhairport\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\",\"name\":\"Niclas Rebbelmund\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"caption\":\"Niclas Rebbelmund\"},\"description\":\"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/niclashco\\\/\"],\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/author\\\/niclas-rebbelmund\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aeroitalia, 9H-GEF - eddh-airport","description":"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/","og_locale":"de_DE","og_type":"article","og_title":"Aeroitalia, 9H-GEF - eddh-airport","og_description":"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.","og_url":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/","og_site_name":"eddh-airport","article_publisher":"https:\/\/www.facebook.com\/eddhairport\/","article_published_time":"2022-07-29T13:01:15+00:00","og_image":[{"url":"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg","type":"","width":"","height":""}],"author":"Niclas Rebbelmund","twitter_card":"summary_large_image","twitter_creator":"@EDDH_airport_de","twitter_site":"@EDDH_airport_de","twitter_misc":{"Verfasst von":"Niclas Rebbelmund","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#article","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/"},"author":{"name":"Niclas Rebbelmund","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe"},"headline":"Aeroitalia, 9H-GEF","datePublished":"2022-07-29T13:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/"},"wordCount":189,"commentCount":0,"publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg","keywords":["737","737-800","Aeroitalia","B737","B737-800","Boeing","Boeing 737","Boeing 737-800","EDDH","HAM","Hamburg Airport"],"articleSection":["Movements EDDH"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/","name":"Aeroitalia, 9H-GEF - eddh-airport","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#primaryimage"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg","datePublished":"2022-07-29T13:01:15+00:00","description":"Erst einige Tage in Diensten der Aeroitalia und schon am Hamburger Flughafen: Am Morgen besuchte 9H-GEF Fuhlsb\u00fcttel.","breadcrumb":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#primaryimage","url":"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg","contentUrl":"https:\/\/www.netairspace.cc\/pic\/519400\/hottestbrick_main.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/aeroitalia-9h-gef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.eddh-airport.de\/eddhairport\/"},{"@type":"ListItem","position":2,"name":"Aeroitalia, 9H-GEF"}]},{"@type":"WebSite","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","name":"eddh-airport","description":"Luftfahrtnews und Planespotting aus Hamburg","publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eddh-airport.de\/eddhairport\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization","name":"eddh-airport","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","contentUrl":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","width":512,"height":512,"caption":"eddh-airport"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eddhairport\/","https:\/\/x.com\/EDDH_airport_de","https:\/\/www.instagram.com\/eddhairport\/?hl=de"]},{"@type":"Person","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe","name":"Niclas Rebbelmund","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","caption":"Niclas Rebbelmund"},"description":"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast","sameAs":["https:\/\/www.instagram.com\/niclashco\/"],"url":"https:\/\/www.eddh-airport.de\/eddhairport\/author\/niclas-rebbelmund\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/comments?post=7284"}],"version-history":[{"count":1,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7284\/revisions"}],"predecessor-version":[{"id":7285,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7284\/revisions\/7285"}],"wp:attachment":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/media?parent=7284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/categories?post=7284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/tags?post=7284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}