{"id":7027,"date":"2022-05-15T16:41:12","date_gmt":"2022-05-15T14:41:12","guid":{"rendered":"https:\/\/www.eddh-airport.de\/eddhairport\/?p=7027"},"modified":"2022-05-22T12:50:35","modified_gmt":"2022-05-22T10:50:35","slug":"saudi-royal-flight-hz-124-4","status":"publish","type":"post","link":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/","title":{"rendered":"Saudi Royal Flight, HZ-124"},"content":{"rendered":"<h6>Saudi Royal Flight, HZ-124<\/h6>\n<p>So langsam kommt wieder Leben in diesen Airbus. Nachdem HZ-124 der Saudi Royal Flight Mitte Februar diesen Jahres frisch lackiert nach Hamburg zur\u00fcckkehrte (wir berichteten), verschwand der Airbus A340-213 zun\u00e4chst wieder in den Hallen der Lufthansa Technik (LHT). Dort ist er bereits nun schon weit mehr als zwei Jahre beheimatet und wird komplett umgebaut und Instand gesetzt. Am heutigen Mittag brach der Vierstrahler dann zu einem ersten Testflug auf.<\/p>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/508186\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/508186\/\"><span style=\"font-size: xx-small;\">HZ-124 at Hamburg &#8211; Fuhlsbuettel (Helmut Schmidt)<br \/>\nby Lars Hentschel on netAirspace<\/span><\/a><\/p>\n<p>Nach einiger Zeit gr\u00f6\u00dftenteils \u00fcber Mecklenburg-Vorpommern und Brandenburg kehrte das mehr als 30 Jahre alte Langstreckenflugzeug wieder nach Fuhlsb\u00fcttel zur\u00fcck. Dabei ist die Maschine mit der Baunummer (MSN) 004 einer der ersten jemals gebauten Airbus A340 und tats\u00e4chlich der allererste in der -200er Variante. Ausgeliefert wurde er jedoch erst am 28. Februar 1997 an die saudi-arabische Regierung nachdem er bereits am 1. April 1992 zum ersten Mal im franz\u00f6sischen Toulouse (TLS) abhob. \u00dcber die ebenfalls saudische Al-Atheer Aviation im Oktober 2012 landete der Jet mit VIP-Kabine dann im September 2014 bei der Saudi Royal Flight. Diese Fluggesellschaft betreibt einige Flugzeug ausschlie\u00dflich f\u00fcr die k\u00f6nigliche Familie des Landes. HZ-124 wird bald auch wieder dazu z\u00e4hlen und uns hoffentlich vorher noch mit dem ein oder anderen Testflug begeistern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saudi Royal Flight, HZ-124 So langsam kommt wieder Leben in diesen Airbus. Nachdem HZ-124 der Saudi Royal Flight Mitte Februar diesen Jahres frisch lackiert nach Hamburg zur\u00fcckkehrte (wir berichteten), verschwand der Airbus A340-213 zun\u00e4chst wieder in den Hallen der Lufthansa Technik (LHT). Dort ist er bereits nun schon weit mehr als zwei Jahre beheimatet und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[80,201,12,378,737,10,11,90,392,63,353],"class_list":["post-7027","post","type-post","status-publish","format-standard","hentry","category-movements-eddh","tag-a340","tag-a340-200","tag-airbus","tag-airbus-a340","tag-airbus-a340-200","tag-eddh","tag-ham","tag-hamburg-airport","tag-lht","tag-lufthansa-technik","tag-saudi-royal-flight"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saudi Royal Flight, HZ-124 - eddh-airport<\/title>\n<meta name=\"description\" content=\"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saudi Royal Flight, HZ-124 - eddh-airport\" \/>\n<meta property=\"og:description\" content=\"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/\" \/>\n<meta property=\"og:site_name\" content=\"eddh-airport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eddhairport\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-15T14:41:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-22T10:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg\" \/>\n<meta name=\"author\" content=\"Niclas Rebbelmund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:site\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niclas Rebbelmund\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/\"},\"author\":{\"name\":\"Niclas Rebbelmund\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\"},\"headline\":\"Saudi Royal Flight, HZ-124\",\"datePublished\":\"2022-05-15T14:41:12+00:00\",\"dateModified\":\"2022-05-22T10:50:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/508186\\\/hottestbrick_main.jpg\",\"keywords\":[\"A340\",\"A340-200\",\"Airbus\",\"Airbus A340\",\"Airbus A340-200\",\"EDDH\",\"HAM\",\"Hamburg Airport\",\"LHT\",\"Lufthansa Technik\",\"Saudi Royal Flight\"],\"articleSection\":[\"Movements EDDH\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/\",\"name\":\"Saudi Royal Flight, HZ-124 - eddh-airport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/508186\\\/hottestbrick_main.jpg\",\"datePublished\":\"2022-05-15T14:41:12+00:00\",\"dateModified\":\"2022-05-22T10:50:35+00:00\",\"description\":\"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/508186\\\/hottestbrick_main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/508186\\\/hottestbrick_main.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/saudi-royal-flight-hz-124-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saudi Royal Flight, HZ-124\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"name\":\"eddh-airport\",\"description\":\"Luftfahrtnews und Planespotting aus Hamburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\",\"name\":\"eddh-airport\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"width\":512,\"height\":512,\"caption\":\"eddh-airport\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eddhairport\\\/\",\"https:\\\/\\\/x.com\\\/EDDH_airport_de\",\"https:\\\/\\\/www.instagram.com\\\/eddhairport\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\",\"name\":\"Niclas Rebbelmund\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"caption\":\"Niclas Rebbelmund\"},\"description\":\"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/niclashco\\\/\"],\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/author\\\/niclas-rebbelmund\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saudi Royal Flight, HZ-124 - eddh-airport","description":"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/","og_locale":"de_DE","og_type":"article","og_title":"Saudi Royal Flight, HZ-124 - eddh-airport","og_description":"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.","og_url":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/","og_site_name":"eddh-airport","article_publisher":"https:\/\/www.facebook.com\/eddhairport\/","article_published_time":"2022-05-15T14:41:12+00:00","article_modified_time":"2022-05-22T10:50:35+00:00","og_image":[{"url":"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg","type":"","width":"","height":""}],"author":"Niclas Rebbelmund","twitter_card":"summary_large_image","twitter_creator":"@EDDH_airport_de","twitter_site":"@EDDH_airport_de","twitter_misc":{"Verfasst von":"Niclas Rebbelmund","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#article","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/"},"author":{"name":"Niclas Rebbelmund","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe"},"headline":"Saudi Royal Flight, HZ-124","datePublished":"2022-05-15T14:41:12+00:00","dateModified":"2022-05-22T10:50:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg","keywords":["A340","A340-200","Airbus","Airbus A340","Airbus A340-200","EDDH","HAM","Hamburg Airport","LHT","Lufthansa Technik","Saudi Royal Flight"],"articleSection":["Movements EDDH"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/","name":"Saudi Royal Flight, HZ-124 - eddh-airport","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#primaryimage"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg","datePublished":"2022-05-15T14:41:12+00:00","dateModified":"2022-05-22T10:50:35+00:00","description":"Am heutigen Mittag brach HZ-124 der Saudi Royal Flight vom Hamburger Flughafen zu einem mehrst\u00fcndigen Testflug auf.","breadcrumb":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#primaryimage","url":"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg","contentUrl":"https:\/\/www.netairspace.cc\/pic\/508186\/hottestbrick_main.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/saudi-royal-flight-hz-124-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.eddh-airport.de\/eddhairport\/"},{"@type":"ListItem","position":2,"name":"Saudi Royal Flight, HZ-124"}]},{"@type":"WebSite","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","name":"eddh-airport","description":"Luftfahrtnews und Planespotting aus Hamburg","publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eddh-airport.de\/eddhairport\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization","name":"eddh-airport","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","contentUrl":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","width":512,"height":512,"caption":"eddh-airport"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eddhairport\/","https:\/\/x.com\/EDDH_airport_de","https:\/\/www.instagram.com\/eddhairport\/?hl=de"]},{"@type":"Person","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe","name":"Niclas Rebbelmund","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","caption":"Niclas Rebbelmund"},"description":"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast","sameAs":["https:\/\/www.instagram.com\/niclashco\/"],"url":"https:\/\/www.eddh-airport.de\/eddhairport\/author\/niclas-rebbelmund\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/comments?post=7027"}],"version-history":[{"count":1,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7027\/revisions"}],"predecessor-version":[{"id":7028,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7027\/revisions\/7028"}],"wp:attachment":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/media?parent=7027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/categories?post=7027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/tags?post=7027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}