{"id":7022,"date":"2022-05-12T16:52:55","date_gmt":"2022-05-12T14:52:55","guid":{"rendered":"https:\/\/www.eddh-airport.de\/eddhairport\/?p=7022"},"modified":"2022-05-12T16:52:55","modified_gmt":"2022-05-12T14:52:55","slug":"government-of-the-united-kingdom-g-gbni","status":"publish","type":"post","link":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/","title":{"rendered":"Government of the United Kingdom, G-GBNI"},"content":{"rendered":"<h6>Government of the United Kingdom, G-GBNI<\/h6>\n<p>G7 Au\u00dfenministertreffen in Wei\u00dfenhaus an der Ostsee. Das h\u00f6rt sich erstmal nach einigen sch\u00f6nen Flugbewegungen auch f\u00fcr den Hamburger Flughafen an, denn der Airport ist der n\u00e4chst gr\u00f6\u00dfere f\u00fcr alle gr\u00f6\u00dferen Flugzeuge weit jenseits von Business-Jets. Vielleicht war jedoch die Erwartungshaltung dann doch vielleicht an mancher Stelle zu hoch, gerade nach dem f\u00fcr Spotter sehr erfolgreichen G20-Gipfel im Jahre 2017 hier in der Stadt. Denn als einzig richtige Regierungsmaschine landete am heutigen Nachmittag mit G-GBNI ein Airbus A321-253NX der britischen Regierung in Fuhlsb\u00fcttel.<\/p>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/507785\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/507785\/\"><span style=\"font-size: xx-small;\">G-GBNI at Hamburg &#8211; Fuhlsbuettel (Helmut Schmidt)<br \/>\nby Lars Hentschel on netAirspace<\/span><\/a><\/p>\n<p>Der Airbus A321neo kam dabei vom Londoner Flughafen Stansted (STN). Noch bis zum 15. Mai dauerte der Gipfel an der Ostsee. Wann genau der Jet mit dem markanten Union Jack des Vereinigten K\u00f6nigreichs wieder abreist ist derweil nicht bekannt. Allerdings konnte man den erst knapp \u00fcber ein Jahr alten A321 bereits in Finkenwerder (XFW) sehen, denn dort wurde der Zweistrahler gefertigt. Jedoch trug das Mittelstreckenflugzeug zu diesem Zeitpunkt noch ein schlichtes wei\u00dfes Kleid, denn zun\u00e4chst wurde es an die ebenfalls britische Titan Airways am 31. M\u00e4rz 2021 ausgeliefert. Seitdem tr\u00e4gt die Maschine die Kennung G-GBNI und erst seit dem 3. April diesen Jahres betreibt Titan Airways sie f\u00fcr die britische Regierung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Government of the United Kingdom, G-GBNI G7 Au\u00dfenministertreffen in Wei\u00dfenhaus an der Ostsee. Das h\u00f6rt sich erstmal nach einigen sch\u00f6nen Flugbewegungen auch f\u00fcr den Hamburger Flughafen an, denn der Airport ist der n\u00e4chst gr\u00f6\u00dfere f\u00fcr alle gr\u00f6\u00dferen Flugzeuge weit jenseits von Business-Jets. Vielleicht war jedoch die Erwartungshaltung dann doch vielleicht an mancher Stelle zu hoch, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[13,14,548,12,471,517,547,10,1411,11,90],"class_list":["post-7022","post","type-post","status-publish","format-standard","hentry","category-movements-eddh","tag-a321","tag-a321neo","tag-a321nx","tag-airbus","tag-airbus-a321","tag-airbus-a321neo","tag-airbus-a321nx","tag-eddh","tag-government-of-the-united-kingdom","tag-ham","tag-hamburg-airport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Government of the United Kingdom, G-GBNI - eddh-airport<\/title>\n<meta name=\"description\" content=\"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Government of the United Kingdom, G-GBNI - eddh-airport\" \/>\n<meta property=\"og:description\" content=\"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/\" \/>\n<meta property=\"og:site_name\" content=\"eddh-airport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eddhairport\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T14:52:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg\" \/>\n<meta name=\"author\" content=\"Niclas Rebbelmund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:site\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niclas Rebbelmund\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/\"},\"author\":{\"name\":\"Niclas Rebbelmund\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\"},\"headline\":\"Government of the United Kingdom, G-GBNI\",\"datePublished\":\"2022-05-12T14:52:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/507785\\\/hottestbrick_main.jpg\",\"keywords\":[\"A321\",\"A321Neo\",\"A321NX\",\"Airbus\",\"Airbus A321\",\"Airbus A321neo\",\"Airbus A321NX\",\"EDDH\",\"Government of the United Kingdom\",\"HAM\",\"Hamburg Airport\"],\"articleSection\":[\"Movements EDDH\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/\",\"name\":\"Government of the United Kingdom, G-GBNI - eddh-airport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/507785\\\/hottestbrick_main.jpg\",\"datePublished\":\"2022-05-12T14:52:55+00:00\",\"description\":\"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/507785\\\/hottestbrick_main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/507785\\\/hottestbrick_main.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/government-of-the-united-kingdom-g-gbni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Government of the United Kingdom, G-GBNI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"name\":\"eddh-airport\",\"description\":\"Luftfahrtnews und Planespotting aus Hamburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\",\"name\":\"eddh-airport\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"width\":512,\"height\":512,\"caption\":\"eddh-airport\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eddhairport\\\/\",\"https:\\\/\\\/x.com\\\/EDDH_airport_de\",\"https:\\\/\\\/www.instagram.com\\\/eddhairport\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\",\"name\":\"Niclas Rebbelmund\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"caption\":\"Niclas Rebbelmund\"},\"description\":\"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/niclashco\\\/\"],\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/author\\\/niclas-rebbelmund\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Government of the United Kingdom, G-GBNI - eddh-airport","description":"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/","og_locale":"de_DE","og_type":"article","og_title":"Government of the United Kingdom, G-GBNI - eddh-airport","og_description":"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.","og_url":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/","og_site_name":"eddh-airport","article_publisher":"https:\/\/www.facebook.com\/eddhairport\/","article_published_time":"2022-05-12T14:52:55+00:00","og_image":[{"url":"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg","type":"","width":"","height":""}],"author":"Niclas Rebbelmund","twitter_card":"summary_large_image","twitter_creator":"@EDDH_airport_de","twitter_site":"@EDDH_airport_de","twitter_misc":{"Verfasst von":"Niclas Rebbelmund","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#article","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/"},"author":{"name":"Niclas Rebbelmund","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe"},"headline":"Government of the United Kingdom, G-GBNI","datePublished":"2022-05-12T14:52:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg","keywords":["A321","A321Neo","A321NX","Airbus","Airbus A321","Airbus A321neo","Airbus A321NX","EDDH","Government of the United Kingdom","HAM","Hamburg Airport"],"articleSection":["Movements EDDH"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/","name":"Government of the United Kingdom, G-GBNI - eddh-airport","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#primaryimage"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg","datePublished":"2022-05-12T14:52:55+00:00","description":"Mit G-GBNI landete am Nachmittag die einzig nennenswerte Maschine im Zusammenhang mit dem aktuellen G7 Au\u00dfenministertreffen an der Ostsee.","breadcrumb":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#primaryimage","url":"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg","contentUrl":"https:\/\/www.netairspace.cc\/pic\/507785\/hottestbrick_main.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/government-of-the-united-kingdom-g-gbni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.eddh-airport.de\/eddhairport\/"},{"@type":"ListItem","position":2,"name":"Government of the United Kingdom, G-GBNI"}]},{"@type":"WebSite","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","name":"eddh-airport","description":"Luftfahrtnews und Planespotting aus Hamburg","publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eddh-airport.de\/eddhairport\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization","name":"eddh-airport","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","contentUrl":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","width":512,"height":512,"caption":"eddh-airport"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eddhairport\/","https:\/\/x.com\/EDDH_airport_de","https:\/\/www.instagram.com\/eddhairport\/?hl=de"]},{"@type":"Person","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe","name":"Niclas Rebbelmund","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","caption":"Niclas Rebbelmund"},"description":"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast","sameAs":["https:\/\/www.instagram.com\/niclashco\/"],"url":"https:\/\/www.eddh-airport.de\/eddhairport\/author\/niclas-rebbelmund\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/comments?post=7022"}],"version-history":[{"count":1,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7022\/revisions"}],"predecessor-version":[{"id":7023,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/7022\/revisions\/7023"}],"wp:attachment":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/media?parent=7022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/categories?post=7022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/tags?post=7022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}