{"id":10386,"date":"2026-04-11T18:21:17","date_gmt":"2026-04-11T16:21:17","guid":{"rendered":"https:\/\/www.eddh-airport.de\/eddhairport\/?p=10386"},"modified":"2026-04-14T10:57:50","modified_gmt":"2026-04-14T08:57:50","slug":"electra-airways-lz-eah","status":"publish","type":"post","link":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/","title":{"rendered":"Electra Airways, LZ-EAH"},"content":{"rendered":"<h6>Electra Airways, LZ-EAH<\/h6>\n<p>Bereits vergangene Woche war f\u00fcr die \u00e4gyptische Air Cairo eine Maschine der bulgarischen Electra Airways nach Hamburg im Einsatz (<a href=\"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eaj\/\">wir berichteten<\/a>). Am heutigen sp\u00e4ten Mittag landete erneut ein Airbus A320-214 der Charterfluggesellschaft im selben Auftrag in Fuhlsb\u00fcttel. Die Maschine mit der Kennung LZ-EAH tr\u00e4gt dabei jedoch noch bis auf die Airlinetitel die komplett vollst\u00e4ndige Lackierung des vorherigen und seit Ende 2023 insolventen Betreibers Ultra Air aus Kolumbien.<\/p>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/715712\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/715712\/\"><span style=\"font-size: xx-small;\">LZ-EAH at Hamburg &#8211; Fuhlsbuettel (Helmut Schmidt)<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><\/p>\n<p>\u00dcber die Piste 15 setzte der mehr als 19 Jahre alte Zweistrahler am Hamburger Flughafen auf und flog nach der Abfertigung auf dem Vorfeld 1 \u00fcber die Startbahn 23 wieder in Richtung Hurghada (HRG) ab. Seit dem 21. Juli 2023 ist der 180-Sitzer nun schon bei Electra Airways im Einsatz. Zuvor war der Jet gerade mal ein knappes Jahr, vom Fr\u00fchjahr 2022 bis Mitte Februar 2023, f\u00fcr die bereits erw\u00e4hnte Ultra Air im Betrieb. Urspr\u00fcnglich wurde der Airbus am 31. Oktober 2006 im franz\u00f6sischen Toulouse (TLS) an Air Arabia ausgeliefert und flog dort bis in den Sp\u00e4tsommer 2012. \u00dcber Rossiya aus Russland und die mexikanische Interjet landete der A320 schlie\u00dflich in Kolumbien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Electra Airways, LZ-EAH Bereits vergangene Woche war f\u00fcr die \u00e4gyptische Air Cairo eine Maschine der bulgarischen Electra Airways nach Hamburg im Einsatz (wir berichteten). Am heutigen sp\u00e4ten Mittag landete erneut ein Airbus A320-214 der Charterfluggesellschaft im selben Auftrag in Fuhlsb\u00fcttel. Die Maschine mit der Kennung LZ-EAH tr\u00e4gt dabei jedoch noch bis auf die Airlinetitel die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[167,290,1559,12,445,518,1557,10,1473,11,90],"class_list":["post-10386","post","type-post","status-publish","format-standard","hentry","category-movements-eddh","tag-a320","tag-a320-200","tag-a320-214","tag-airbus","tag-airbus-a320","tag-airbus-a320-200","tag-airbus-a320-214","tag-eddh","tag-electra-airways","tag-ham","tag-hamburg-airport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Electra Airways, LZ-EAH - eddh-airport<\/title>\n<meta name=\"description\" content=\"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electra Airways, LZ-EAH - eddh-airport\" \/>\n<meta property=\"og:description\" content=\"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/\" \/>\n<meta property=\"og:site_name\" content=\"eddh-airport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eddhairport\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T16:21:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T08:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg\" \/>\n<meta name=\"author\" content=\"Niclas Rebbelmund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:site\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niclas Rebbelmund\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/\"},\"author\":{\"name\":\"Niclas Rebbelmund\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\"},\"headline\":\"Electra Airways, LZ-EAH\",\"datePublished\":\"2026-04-11T16:21:17+00:00\",\"dateModified\":\"2026-04-14T08:57:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/715712\\\/hottestbrick_main.jpg\",\"keywords\":[\"A320\",\"A320-200\",\"A320-214\",\"Airbus\",\"Airbus A320\",\"Airbus A320-200\",\"Airbus A320-214\",\"EDDH\",\"Electra Airways\",\"HAM\",\"Hamburg Airport\"],\"articleSection\":[\"Movements EDDH\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/\",\"name\":\"Electra Airways, LZ-EAH - eddh-airport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/715712\\\/hottestbrick_main.jpg\",\"datePublished\":\"2026-04-11T16:21:17+00:00\",\"dateModified\":\"2026-04-14T08:57:50+00:00\",\"description\":\"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/715712\\\/hottestbrick_main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/715712\\\/hottestbrick_main.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/electra-airways-lz-eah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electra Airways, LZ-EAH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"name\":\"eddh-airport\",\"description\":\"Luftfahrtnews und Planespotting aus Hamburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\",\"name\":\"eddh-airport\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"width\":512,\"height\":512,\"caption\":\"eddh-airport\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eddhairport\\\/\",\"https:\\\/\\\/x.com\\\/EDDH_airport_de\",\"https:\\\/\\\/www.instagram.com\\\/eddhairport\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/person\\\/69e52086d712e506636c8f4c5f088abe\",\"name\":\"Niclas Rebbelmund\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g\",\"caption\":\"Niclas Rebbelmund\"},\"description\":\"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/niclashco\\\/\"],\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/author\\\/niclas-rebbelmund\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electra Airways, LZ-EAH - eddh-airport","description":"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/","og_locale":"de_DE","og_type":"article","og_title":"Electra Airways, LZ-EAH - eddh-airport","og_description":"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.","og_url":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/","og_site_name":"eddh-airport","article_publisher":"https:\/\/www.facebook.com\/eddhairport\/","article_published_time":"2026-04-11T16:21:17+00:00","article_modified_time":"2026-04-14T08:57:50+00:00","og_image":[{"url":"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg","type":"","width":"","height":""}],"author":"Niclas Rebbelmund","twitter_card":"summary_large_image","twitter_creator":"@EDDH_airport_de","twitter_site":"@EDDH_airport_de","twitter_misc":{"Verfasst von":"Niclas Rebbelmund","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#article","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/"},"author":{"name":"Niclas Rebbelmund","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe"},"headline":"Electra Airways, LZ-EAH","datePublished":"2026-04-11T16:21:17+00:00","dateModified":"2026-04-14T08:57:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg","keywords":["A320","A320-200","A320-214","Airbus","Airbus A320","Airbus A320-200","Airbus A320-214","EDDH","Electra Airways","HAM","Hamburg Airport"],"articleSection":["Movements EDDH"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/","name":"Electra Airways, LZ-EAH - eddh-airport","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#primaryimage"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg","datePublished":"2026-04-11T16:21:17+00:00","dateModified":"2026-04-14T08:57:50+00:00","description":"Erneut landete heute mit LZ-EAH ein Airbus A320 der Electra Airways im Auftrag f\u00fcr Air Cairo am Hamburger Flughafen.","breadcrumb":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#primaryimage","url":"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg","contentUrl":"https:\/\/www.netairspace.cc\/pic\/715712\/hottestbrick_main.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/electra-airways-lz-eah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.eddh-airport.de\/eddhairport\/"},{"@type":"ListItem","position":2,"name":"Electra Airways, LZ-EAH"}]},{"@type":"WebSite","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","name":"eddh-airport","description":"Luftfahrtnews und Planespotting aus Hamburg","publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eddh-airport.de\/eddhairport\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization","name":"eddh-airport","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","contentUrl":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","width":512,"height":512,"caption":"eddh-airport"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eddhairport\/","https:\/\/x.com\/EDDH_airport_de","https:\/\/www.instagram.com\/eddhairport\/?hl=de"]},{"@type":"Person","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/person\/69e52086d712e506636c8f4c5f088abe","name":"Niclas Rebbelmund","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d84f2b77774e9493691ea91c216d4e4e5412d631f5fe9806ac1d1d54bd3c30cb?s=96&d=mm&r=g","caption":"Niclas Rebbelmund"},"description":"34 Jahre, Team Nikon, Aviation &amp; Fotografie Enthusiast","sameAs":["https:\/\/www.instagram.com\/niclashco\/"],"url":"https:\/\/www.eddh-airport.de\/eddhairport\/author\/niclas-rebbelmund\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/10386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/comments?post=10386"}],"version-history":[{"count":1,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/10386\/revisions"}],"predecessor-version":[{"id":10387,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/posts\/10386\/revisions\/10387"}],"wp:attachment":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/media?parent=10386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/categories?post=10386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/tags?post=10386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}