{"id":17,"date":"2018-04-29T23:09:25","date_gmt":"2018-04-29T21:09:25","guid":{"rendered":"https:\/\/www.eddh-airport.de\/eddhairport\/?page_id=17"},"modified":"2025-08-25T14:54:27","modified_gmt":"2025-08-25T12:54:27","slug":"edhi","status":"publish","type":"page","link":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/","title":{"rendered":"EDHI"},"content":{"rendered":"<p>Das Airbuswerk in Finkenwerder verf\u00fcgt \u00fcber einige Fotopositionen. Auch wer den Sprung \u00fcber die Elbe, bspw. auf Grund des Nadel\u00f6hrs Elbtunnel, scheut, kann unter gewissen Umst\u00e4nden trotzdem Fotos von landenden Maschinen auf den Werksflughafen machen. Neben Landungen und Starts finden auch einige Tests auf der Bahn in Finkenwerder statt. Diese lassen sich nat\u00fcrlich nur direkt am Werksflughafen aufnehmen. Viele Positionen sind daf\u00fcr auch nutzbar, dies wird jedoch nicht noch einmal explizit erw\u00e4hnt.<br \/>\nAuf dieser Seite geben wir euch eine \u00dcbersicht der vielen M\u00f6glichkeiten. Auf der folgenden Karte markieren die blauen Punkte die einzelnen Spotterpunkte.<\/p>\n<p>Sollten euch Fehler auffallen oder ihr m\u00f6chtet etwas erg\u00e4nzen, nehmt gerne Kontakt mit uns auf. Dazu findet ihr unten auf der Seite ein Kontaktformular.<\/p>\n<p><iframe src=\"https:\/\/www.google.com\/maps\/d\/u\/0\/embed?mid=1wc9Kz58WytYrL0R4AimHFHSewTWbvLek\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div class=\"su-accordion su-u-trim\">\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 1 - Jenischpark (Vormittagsseite)<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/411996\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/411996\/\"><span style=\"font-size: xx-small;\">F-WWSZ at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Der Jenischpark auf der n\u00f6rdlichen Elbseite eignet sich hervorragend um Landungen auf die Landebahn 23 aufzunehmen. Wer aus zeitlichen Gr\u00fcnden n\u00f6rdlich der Elbe bleiben muss, kann von hier aus Fotos der ankommenden Maschinen in der Luft aufnehmen.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">100-600 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 2 - Jenischpark (Nachmittagsseite)<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/406320\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/406320\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/406320\/\"><span style=\"font-size: xx-small;\">D-AZAO at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Der Jenischpark auf der n\u00f6rdlichen Elbseite eignet sich hervorragend um Landungen auf die Landebahn 23 aufzunehmen. Wer aus zeitlichen Gr\u00fcnden n\u00f6rdlich der Elbe bleiben muss, kann von hier aus Fotos der ankommenden Maschinen in der Luft aufnehmen. Direkt neben dem Jenischhaus kann man sich gut platzieren.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von mittags bis abends<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">100-600 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 3 - Elbe<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/386072\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/386072\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/386072\/\"><span style=\"font-size: xx-small;\">F-WMIL at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Direkt an der Elbe am Beginn der Liegewiese kann man sich gut gerade in den Sommermonaten ab Nachmittags positionieren, um landende Flugzeuge auf die Landebahn 23 aufzunehmen. Wenn ihr aus der Stadt kommt erspart ihr euch auch hier die Fahrt durch den Elbtunnel. Hier ben\u00f6tigt ihr allerdings gerade f\u00fcr kleinere Flugzeuge gro\u00dfe Brennweiten.\u00a0<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von mittags bis abends<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">100-600 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Ein nahegelegenes Restaurant und ein Imbiss lassen kaum W\u00fcnsche offen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 4 - Aussichtsturm<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/383082\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/383082\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/383082\/\"><span style=\"font-size: xx-small;\">EI-FGN at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Direkt an der Elbe liegt der Aussichtsturm der eigentlich urspr\u00fcnglich zur Beobachtung des Schiffsverkehrs gedacht war. Von dort aus habt ihr jedoch einen guten Blick am Vormittag auf landende Flugzeuge der Landebahn 23. Sofern die B\u00f6schung nicht zu hoch gewachsen ist, k\u00f6nnen hier auch Fotos vom Wendehammer gemacht werden. Auch parkende Flugzeuge (selten) k\u00f6nnen dort vor den Geb\u00e4ude von Airbus mit viel Brennweite aufgenommen werden.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts (unter Umst\u00e4nden) &#8211; von morgens bis mittags<br \/>\n05 Landungen (unter Umst\u00e4nden) &#8211; von morgens bis mittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-600 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 5 - Airbus Periport<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/682863\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/682863\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/682863\/\"><span style=\"font-size: xx-small;\">ZK-NNH at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Direkt neben dem Haupteingang des Airbuswerks liegt eine Position direkt am Zaun des neu gebauten REWE. Auf dessen Parkplatz k\u00f6nnt ihr parken und eure Leiter an den Zaun stellen (nur noch bedingt m\u00f6glich, da der Zaun erh\u00f6ht wurde. Allerdings ist es hier m\u00f6glich, dass euch ein Bus oder anderes Fahrzeug ins Bild f\u00e4hrt.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts (unter Umst\u00e4nden) &#8211; von morgens bis mittags<br \/>\n05 Landungen &#8211; von morgens bis mittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Der nahegelegene REWE l\u00e4sst keine W\u00fcnsche offen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 6 - Deich<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<h5>Spottingposition 6 &#8211; Deich<\/h5>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/408758\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/408758\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/408758\/\"><span style=\"font-size: xx-small;\">B-6548 at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Auf dem Deich an der Stra\u00dfe &#8220;Ne\u00dfdeich&#8221; lassen sich die Maschinen mit den Hallen und Geb\u00e4ude des Airportwerks im Hintergrund aufnehmen.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts &#8211; von morgens bis mittags<br \/>\n05 Landungen (unter Umst\u00e4nden) &#8211; von morgens bis mittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 7 - Deich (weiter oben)<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/398039\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/398039\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/398039\/\"><span style=\"font-size: xx-small;\">D-AZAB at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Weiter oben auf dem selben Deich wie Position 6 lassen sich mit viel Brennweite geparkte Flugzeuge vor der Feuerwehr des Werksgel\u00e4ndes aufnehmen. Auch das Lineup auf die Bahn bei 23 Takeoff ist von dort mit viel Brennweite m\u00f6glich. Nat\u00fcrlich sind auch hier alle weiteren Bewegungen auf der Bahn m\u00f6glich.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts &#8211; von morgens bis mittags<br \/>\n05 Landungen (unter Umst\u00e4nden) &#8211; von morgens bis mittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 8 - Aussichts-Plattform Airbus<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<h5>Spottingposition 8 &#8211; Aussichts-Plattform Airbus<\/h5>\n<p><a href=\"https:\/\/www.netairspace.cc\/pic\/376940\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/376940\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/376940\/\"><span style=\"font-size: xx-small;\">F-WWAL at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Extra zur Beobachtung und zum Fotografieren der Flugzeuge auf dem Werksgel\u00e4nde hat Airbus einen kleinen H\u00fcgel mit samt Parkplatz gebaut. Hier gibt es sehr vielf\u00e4ltige M\u00f6glichkeiten die Maschinen aufzunehmen. Ist der H\u00fcgel \u00fcberf\u00fcllt, kann man sich auch alternativ mit einer Leiter unten an den Zaun stellen.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts (A320-Family dort schon relativ hoch) &#8211; von morgens bis mittags<br \/>\n05 Landungen &#8211; von morgens bis mittags<br \/>\n05 Starts &#8211; von morgens bis mittags<br \/>\n23 Lineup &#8211; von vormittags bis nachmittags<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-400 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 9 - Entlang der Runway<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/383170\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/383170\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/383170\/\"><span style=\"font-size: xx-small;\">D-AUAP at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">\u00dcberall entlang der Runway ist es m\u00f6glich sich mit einer Leiter zu positionieren und Fotos der Maschinen auf der Start- und Landebahn zu machen.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von morgens bis mittags<br \/>\n23 Starts (Flugzeuge je nach Position schon sehr hoch) &#8211; von morgens bis mittags<br \/>\n05 Landungen &#8211; von morgens bis mittags<br \/>\n05 Starts &#8211; von morgens bis mittags<br \/>\n<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">28-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 10 - Deich (am Bahnkopf)<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<em>Beispielfoto folgt!<\/em><\/p>\n<p><span style=\"font-weight: 400;\">Auf dem Deich am Bahnkopf lassen sich Flugzeuge die auf der Runway sind ablichten.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen (unter Umst\u00e4nden) &#8211; von morgens bis mittags<br \/>\n05 Landungen &#8211; von morgens bis mittags<br \/>\n05 Starts &#8211; von morgens bis mittags<br \/>\n<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 11 - Bahnkopf<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/460131\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/460131\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/460131\/\"><span style=\"font-size: xx-small;\">D-AVWG at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Direkt am Bahnkopf k\u00f6nnen Fotos die Landebahn runter gemacht werden. Auch das Wenden im neuen Wendehammer ist hier fotografisch festzuhalten. Allerdings wird hier eine Leiter daf\u00fcr ben\u00f6tigt.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen (unter Umst\u00e4nden) &#8211; von mittags bis nachmittags<br \/>\n05 Starts &#8211; von mittags bis nachmittags<br \/>\n<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">28-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 12 - Airbus S\u00fcdtor<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/379915\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/379915\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/379915\/\"><span style=\"font-size: xx-small;\">F-WMIL at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Neben dem Airbus S\u00fcdtor f\u00fchrt eine kleine Stra\u00dfe bis zum Zaun. Dort ben\u00f6tigt ihr eine Leiter und k\u00f6nnt Flugzeuge die im alten Wendehammer wenden aufnehmen, auf der 23 gelandet sind, auf der 05 starten oder auch auf der 05 landen. ACHTUNG: Die Durchfahrt der Stra\u00dfe ist nicht gestattet!<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von nachmittags bis abends<br \/>\n05 Landungen &#8211; von nachmittags bis abends<br \/>\n05 Starts &#8211; von nachmittags bis abends<br \/>\n<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">50-300 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Spottingposition 13 - Deich (am S\u00fcdtor)<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<a href=\"https:\/\/www.netairspace.cc\/pic\/347287\/\"><img decoding=\"async\" src=\"https:\/\/www.netairspace.cc\/pic\/347287\/hottestbrick_main.jpg\" alt=\"Aviation photo\" \/><\/a><br \/>\n<a href=\"https:\/\/www.netairspace.cc\/pic\/347287\/\"><span style=\"font-size: xx-small;\">D-AVXN at Hamburg &#8211; Finkenwerder<br \/>\nby Niclas Rebbelmund on netAirspace<\/span><\/a><br \/>\n<span style=\"font-weight: 400;\">Hier k\u00f6nnt ihr \u00e4hnliche Bilder wie bei der Position 12 aufnehmen. Allerdings ben\u00f6tigt ihr hier keine Leiter, sondern braucht nur auf den Deich hoch. Allerdings k\u00f6nnte es dann sein, dass ihr andere Spotter die an Position 12 stehen im Bild habt oder den Zaun. Dazu ben\u00f6tigt ihr etwas mehr Brennweite als an Position 12.<\/span><\/p>\n<h6>Nutzbar (Licht und Richtung):<\/h6>\n<p><span style=\"font-weight: 400;\">23 Landungen &#8211; von nachmittags bis abends<br \/>\n05 Landungen &#8211; von nachmittags bis abends<br \/>\n05 Starts &#8211; von nachmittags bis abends<br \/>\n<\/span><\/p>\n<h6>Brennweiten:<\/h6>\n<p><span style=\"font-weight: 400;\">70-400 mm<\/span><\/p>\n<h6>Verpflegung:<\/h6>\n<p><span style=\"font-weight: 400;\">Hier m\u00fcsst ihr euch etwas mitbringen.<\/span><br \/>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Airbuswerk in Finkenwerder verf\u00fcgt \u00fcber einige Fotopositionen. Auch wer den Sprung \u00fcber die Elbe, bspw. auf Grund des Nadel\u00f6hrs Elbtunnel, scheut, kann unter gewissen Umst\u00e4nden trotzdem Fotos von landenden Maschinen auf den Werksflughafen machen. Neben Landungen und Starts finden auch einige Tests auf der Bahn in Finkenwerder statt. Diese lassen sich nat\u00fcrlich nur direkt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EDHI - eddh-airport<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EDHI - eddh-airport\" \/>\n<meta property=\"og:description\" content=\"Das Airbuswerk in Finkenwerder verf\u00fcgt \u00fcber einige Fotopositionen. Auch wer den Sprung \u00fcber die Elbe, bspw. auf Grund des Nadel\u00f6hrs Elbtunnel, scheut, kann unter gewissen Umst\u00e4nden trotzdem Fotos von landenden Maschinen auf den Werksflughafen machen. Neben Landungen und Starts finden auch einige Tests auf der Bahn in Finkenwerder statt. Diese lassen sich nat\u00fcrlich nur direkt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/\" \/>\n<meta property=\"og:site_name\" content=\"eddh-airport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eddhairport\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T12:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EDDH_airport_de\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/\",\"name\":\"EDHI - eddh-airport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/411996\\\/hottestbrick_main.jpg\",\"datePublished\":\"2018-04-29T21:09:25+00:00\",\"dateModified\":\"2025-08-25T12:54:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/411996\\\/hottestbrick_main.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netairspace.cc\\\/pic\\\/411996\\\/hottestbrick_main.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/edhi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotopositionen\",\"item\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/fotopositionen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EDHI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#website\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"name\":\"eddh-airport\",\"description\":\"Luftfahrtnews und Planespotting aus Hamburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#organization\",\"name\":\"eddh-airport\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg\",\"width\":512,\"height\":512,\"caption\":\"eddh-airport\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eddh-airport.de\\\/eddhairport\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eddhairport\\\/\",\"https:\\\/\\\/x.com\\\/EDDH_airport_de\",\"https:\\\/\\\/www.instagram.com\\\/eddhairport\\\/?hl=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EDHI - eddh-airport","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/","og_locale":"de_DE","og_type":"article","og_title":"EDHI - eddh-airport","og_description":"Das Airbuswerk in Finkenwerder verf\u00fcgt \u00fcber einige Fotopositionen. Auch wer den Sprung \u00fcber die Elbe, bspw. auf Grund des Nadel\u00f6hrs Elbtunnel, scheut, kann unter gewissen Umst\u00e4nden trotzdem Fotos von landenden Maschinen auf den Werksflughafen machen. Neben Landungen und Starts finden auch einige Tests auf der Bahn in Finkenwerder statt. Diese lassen sich nat\u00fcrlich nur direkt [&hellip;]","og_url":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/","og_site_name":"eddh-airport","article_publisher":"https:\/\/www.facebook.com\/eddhairport\/","article_modified_time":"2025-08-25T12:54:27+00:00","og_image":[{"url":"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EDDH_airport_de","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/","name":"EDHI - eddh-airport","isPartOf":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/#primaryimage"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg","datePublished":"2018-04-29T21:09:25+00:00","dateModified":"2025-08-25T12:54:27+00:00","breadcrumb":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/#primaryimage","url":"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg","contentUrl":"https:\/\/www.netairspace.cc\/pic\/411996\/hottestbrick_main.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/edhi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.eddh-airport.de\/eddhairport\/"},{"@type":"ListItem","position":2,"name":"Fotopositionen","item":"https:\/\/www.eddh-airport.de\/eddhairport\/fotopositionen\/"},{"@type":"ListItem","position":3,"name":"EDHI"}]},{"@type":"WebSite","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#website","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","name":"eddh-airport","description":"Luftfahrtnews und Planespotting aus Hamburg","publisher":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eddh-airport.de\/eddhairport\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#organization","name":"eddh-airport","url":"https:\/\/www.eddh-airport.de\/eddhairport\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/","url":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","contentUrl":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-content\/uploads\/2018\/10\/cropped-Neues-Logo-blau-eine-Ebene-2.jpg","width":512,"height":512,"caption":"eddh-airport"},"image":{"@id":"https:\/\/www.eddh-airport.de\/eddhairport\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eddhairport\/","https:\/\/x.com\/EDDH_airport_de","https:\/\/www.instagram.com\/eddhairport\/?hl=de"]}]}},"_links":{"self":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":11,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":10019,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/pages\/17\/revisions\/10019"}],"up":[{"embeddable":true,"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/pages\/13"}],"wp:attachment":[{"href":"https:\/\/www.eddh-airport.de\/eddhairport\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}